{"id":5303,"count":1,"description":"","link":"https:\/\/www.ofmconv.net\/es\/tag\/maximilien-sauge-ofmconv\/","name":"Maximilien SAUGE OFMConv","slug":"maximilien-sauge-ofmconv","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.ofmconv.net\/es\/wp-json\/wp\/v2\/tags\/5303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ofmconv.net\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.ofmconv.net\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.ofmconv.net\/es\/wp-json\/wp\/v2\/posts?tags=5303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}